{"id":34924,"date":"2022-08-02T12:22:04","date_gmt":"2022-08-02T10:22:04","guid":{"rendered":"https:\/\/www.mesvendanges.com\/shop\/uncategorized\/les-galets-2\/"},"modified":"2023-12-05T17:58:09","modified_gmt":"2023-12-05T16:58:09","slug":"les-galets-estezargues-vign-d-2011-75cl","status":"publish","type":"product","link":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/","title":{"rendered":"LES GALETS"},"content":{"rendered":"<p>Voici pour nous le vin de tous les jours le plus convaincant! C&#8217;est un vin gourmand, fruit\u00e9, qui r\u00e9jouira tout le monde et qui s&#8217;accomode de presque toutes les tables!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici pour nous le vin de tous les jours le plus convaincant! C&#8217;est un vin gourmand, fruit\u00e9, qui r\u00e9jouira tout le monde et qui s&#8217;accomode de presque toutes les tables!!!<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3740],"product_tag":[],"class_list":["post-34924","product","type-product","status-publish","product_cat-wines","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LES GALETS - Mes Vendanges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LES GALETS - Mes Vendanges\" \/>\n<meta property=\"og:description\" content=\"Voici pour nous le vin de tous les jours le plus convaincant! C&#8217;est un vin gourmand, fruit\u00e9, qui r\u00e9jouira tout le monde et qui s&#8217;accomode de presque toutes les tables!!!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Vendanges\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T16:58:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/les-galets-estezargues-vign-d-2011-75cl\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/les-galets-estezargues-vign-d-2011-75cl\\\/\",\"name\":\"LES GALETS - Mes Vendanges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\"},\"datePublished\":\"2022-08-02T10:22:04+00:00\",\"dateModified\":\"2023-12-05T16:58:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/les-galets-estezargues-vign-d-2011-75cl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/les-galets-estezargues-vign-d-2011-75cl\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/les-galets-estezargues-vign-d-2011-75cl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LES GALETS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"name\":\"Mes Vendanges\",\"description\":\"Des journ\u00e9es enti\u00e8res dans les vignes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\",\"name\":\"Mes Vendanges\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"width\":851,\"height\":260,\"caption\":\"Mes Vendanges\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LES GALETS - Mes Vendanges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/","og_locale":"en_US","og_type":"article","og_title":"LES GALETS - Mes Vendanges","og_description":"Voici pour nous le vin de tous les jours le plus convaincant! C&#8217;est un vin gourmand, fruit\u00e9, qui r\u00e9jouira tout le monde et qui s&#8217;accomode de presque toutes les tables!!!","og_url":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/","og_site_name":"Mes Vendanges","article_modified_time":"2023-12-05T16:58:09+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/","url":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/","name":"LES GALETS - Mes Vendanges","isPartOf":{"@id":"https:\/\/www.mesvendanges.com\/en\/#website"},"datePublished":"2022-08-02T10:22:04+00:00","dateModified":"2023-12-05T16:58:09+00:00","breadcrumb":{"@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/les-galets-estezargues-vign-d-2011-75cl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mesvendanges.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.mesvendanges.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"LES GALETS"}]},{"@type":"WebSite","@id":"https:\/\/www.mesvendanges.com\/en\/#website","url":"https:\/\/www.mesvendanges.com\/en\/","name":"Mes Vendanges","description":"Des journ\u00e9es enti\u00e8res dans les vignes","publisher":{"@id":"https:\/\/www.mesvendanges.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesvendanges.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mesvendanges.com\/en\/#organization","name":"Mes Vendanges","url":"https:\/\/www.mesvendanges.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","width":851,"height":260,"caption":"Mes Vendanges"},"image":{"@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product\/34924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/media?parent=34924"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_brand?post=34924"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_cat?post=34924"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_tag?post=34924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}