{"id":40636,"date":"2022-08-02T14:47:56","date_gmt":"2022-08-02T12:47:56","guid":{"rendered":"https:\/\/www.mesvendanges.com\/shop\/uncategorized\/javernieres-3\/"},"modified":"2023-12-05T16:08:21","modified_gmt":"2023-12-05T15:08:21","slug":"javernieres-desvignes-louis-claude-2016-75cl","status":"publish","type":"product","link":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/","title":{"rendered":"JAVERNIERES"},"content":{"rendered":"<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":70013,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3740],"product_tag":[],"class_list":["post-40636","product","type-product","status-publish","has-post-thumbnail","product_cat-wines","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JAVERNIERES - Mes Vendanges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JAVERNIERES - Mes Vendanges\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Vendanges\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T15:08:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2023\/12\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/\",\"name\":\"JAVERNIERES - Mes Vendanges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png\",\"datePublished\":\"2022-08-02T12:47:56+00:00\",\"dateModified\":\"2023-12-05T15:08:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png\",\"contentUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png\",\"width\":480,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/javernieres-desvignes-louis-claude-2016-75cl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JAVERNIERES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"name\":\"Mes Vendanges\",\"description\":\"Des journ\u00e9es enti\u00e8res dans les vignes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\",\"name\":\"Mes Vendanges\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"width\":851,\"height\":260,\"caption\":\"Mes Vendanges\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JAVERNIERES - Mes Vendanges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/","og_locale":"en_US","og_type":"article","og_title":"JAVERNIERES - Mes Vendanges","og_url":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/","og_site_name":"Mes Vendanges","article_modified_time":"2023-12-05T15:08:21+00:00","og_image":[{"width":480,"height":1500,"url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2023\/12\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/","url":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/","name":"JAVERNIERES - Mes Vendanges","isPartOf":{"@id":"https:\/\/www.mesvendanges.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/#primaryimage"},"image":{"@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2023\/12\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png","datePublished":"2022-08-02T12:47:56+00:00","dateModified":"2023-12-05T15:08:21+00:00","breadcrumb":{"@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/#primaryimage","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2023\/12\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2023\/12\/domaine-louis-claude-desvignes-morgon-javernieres-2016.png","width":480,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/javernieres-desvignes-louis-claude-2016-75cl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mesvendanges.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.mesvendanges.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"JAVERNIERES"}]},{"@type":"WebSite","@id":"https:\/\/www.mesvendanges.com\/en\/#website","url":"https:\/\/www.mesvendanges.com\/en\/","name":"Mes Vendanges","description":"Des journ\u00e9es enti\u00e8res dans les vignes","publisher":{"@id":"https:\/\/www.mesvendanges.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesvendanges.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mesvendanges.com\/en\/#organization","name":"Mes Vendanges","url":"https:\/\/www.mesvendanges.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","width":851,"height":260,"caption":"Mes Vendanges"},"image":{"@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product\/40636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/media\/70013"}],"wp:attachment":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/media?parent=40636"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_brand?post=40636"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_cat?post=40636"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_tag?post=40636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}