{"id":73233,"date":"2024-01-28T18:54:08","date_gmt":"2024-01-28T17:54:08","guid":{"rendered":"https:\/\/www.mesvendanges.com\/shop\/uncategorized\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/"},"modified":"2024-11-27T17:15:29","modified_gmt":"2024-11-27T16:15:29","slug":"cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl","status":"publish","type":"product","link":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/","title":{"rendered":"COTE DU PY LES IMPENITENTS MAGNUM"},"content":{"rendered":"<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3740],"product_tag":[],"class_list":["post-73233","product","type-product","status-publish","product_cat-wines","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COTE DU PY LES IMPENITENTS MAGNUM - Mes Vendanges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COTE DU PY LES IMPENITENTS MAGNUM - Mes Vendanges\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Vendanges\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T16:15:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\\\/\",\"name\":\"COTE DU PY LES IMPENITENTS MAGNUM - Mes Vendanges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\"},\"datePublished\":\"2024-01-28T17:54:08+00:00\",\"dateModified\":\"2024-11-27T16:15:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/wines\\\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COTE DU PY LES IMPENITENTS MAGNUM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"name\":\"Mes Vendanges\",\"description\":\"Des journ\u00e9es enti\u00e8res dans les vignes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\",\"name\":\"Mes Vendanges\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"width\":851,\"height\":260,\"caption\":\"Mes Vendanges\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COTE DU PY LES IMPENITENTS MAGNUM - Mes Vendanges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/","og_locale":"en_US","og_type":"article","og_title":"COTE DU PY LES IMPENITENTS MAGNUM - Mes Vendanges","og_url":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/","og_site_name":"Mes Vendanges","article_modified_time":"2024-11-27T16:15:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/","url":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/","name":"COTE DU PY LES IMPENITENTS MAGNUM - Mes Vendanges","isPartOf":{"@id":"https:\/\/www.mesvendanges.com\/en\/#website"},"datePublished":"2024-01-28T17:54:08+00:00","dateModified":"2024-11-27T16:15:29+00:00","breadcrumb":{"@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesvendanges.com\/en\/shop\/wines\/cote-du-py-les-impenitents-magnum-desvignes-louis-claude-2022-150cl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mesvendanges.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.mesvendanges.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"COTE DU PY LES IMPENITENTS MAGNUM"}]},{"@type":"WebSite","@id":"https:\/\/www.mesvendanges.com\/en\/#website","url":"https:\/\/www.mesvendanges.com\/en\/","name":"Mes Vendanges","description":"Des journ\u00e9es enti\u00e8res dans les vignes","publisher":{"@id":"https:\/\/www.mesvendanges.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesvendanges.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mesvendanges.com\/en\/#organization","name":"Mes Vendanges","url":"https:\/\/www.mesvendanges.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","width":851,"height":260,"caption":"Mes Vendanges"},"image":{"@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product\/73233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/media?parent=73233"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_brand?post=73233"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_cat?post=73233"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/en\/wp-json\/wp\/v2\/product_tag?post=73233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}