{"id":45972,"date":"2022-08-02T17:00:52","date_gmt":"2022-08-02T15:00:52","guid":{"rendered":"https:\/\/www.mesvendanges.com\/shop\/non%20class\u00e9\/corcelette-2\/"},"modified":"2023-12-05T15:34:15","modified_gmt":"2023-12-05T14:34:15","slug":"corcelette-desvignes-louis-claude-2020-75cl","status":"publish","type":"product","link":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/","title":{"rendered":"CORCELETTE"},"content":{"rendered":"<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":27552,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3736],"product_tag":[],"class_list":["post-45972","product","type-product","status-publish","has-post-thumbnail","product_cat-vins","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CORCELETTE - Mes Vendanges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORCELETTE - Mes Vendanges\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Vendanges\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T14:34:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/07\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png\" \/>\n\t<meta property=\"og:image:width\" content=\"508\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/\",\"name\":\"CORCELETTE - Mes Vendanges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png\",\"datePublished\":\"2022-08-02T15:00:52+00:00\",\"dateModified\":\"2023-12-05T14:34:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png\",\"contentUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png\",\"width\":508,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/corcelette-desvignes-louis-claude-2020-75cl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CORCELETTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"name\":\"Mes Vendanges\",\"description\":\"Des journ\u00e9es enti\u00e8res dans les vignes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\",\"name\":\"Mes Vendanges\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"width\":851,\"height\":260,\"caption\":\"Mes Vendanges\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORCELETTE - Mes Vendanges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/","og_locale":"fr_FR","og_type":"article","og_title":"CORCELETTE - Mes Vendanges","og_url":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/","og_site_name":"Mes Vendanges","article_modified_time":"2023-12-05T14:34:15+00:00","og_image":[{"width":508,"height":1500,"url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/07\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/","url":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/","name":"CORCELETTE - Mes Vendanges","isPartOf":{"@id":"https:\/\/www.mesvendanges.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/#primaryimage"},"image":{"@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/07\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png","datePublished":"2022-08-02T15:00:52+00:00","dateModified":"2023-12-05T14:34:15+00:00","breadcrumb":{"@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/#primaryimage","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/07\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/07\/domaine-louis-claude-desvignes-morgon-corcelette-2020-png.png","width":508,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/corcelette-desvignes-louis-claude-2020-75cl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mesvendanges.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.mesvendanges.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"CORCELETTE"}]},{"@type":"WebSite","@id":"https:\/\/www.mesvendanges.com\/en\/#website","url":"https:\/\/www.mesvendanges.com\/en\/","name":"Mes Vendanges","description":"Des journ\u00e9es enti\u00e8res dans les vignes","publisher":{"@id":"https:\/\/www.mesvendanges.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesvendanges.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mesvendanges.com\/en\/#organization","name":"Mes Vendanges","url":"https:\/\/www.mesvendanges.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","width":851,"height":260,"caption":"Mes Vendanges"},"image":{"@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product\/45972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/media\/27552"}],"wp:attachment":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/media?parent=45972"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_brand?post=45972"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_cat?post=45972"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_tag?post=45972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}