{"id":48189,"date":"2022-08-02T17:34:21","date_gmt":"2022-08-02T15:34:21","guid":{"rendered":"https:\/\/www.mesvendanges.com\/shop\/non%20class\u00e9\/barbera-dalba-bricco-dei-merli\/"},"modified":"2023-12-05T13:50:39","modified_gmt":"2023-12-05T12:50:39","slug":"barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl","status":"publish","type":"product","link":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/","title":{"rendered":"BARBERA D&rsquo;ALBA BRICCO DEI MERLI"},"content":{"rendered":"<p>Barbera d&rsquo;Alba vinifi\u00e9 et \u00e9lev\u00e9 dans de grands foudres slov\u00e8nes. C&rsquo;est un vin \u00e0 la fois structur\u00e9, mais qui garde la finesse, le c\u00f4t\u00e9 a\u00e9rien des vins du domaine. Tr\u00e8s jolie d\u00e9finition de l&rsquo;aromatique, tout est d\u00e9taill\u00e9 et tr\u00e8s \u00e9l\u00e9gant. Un vin tr\u00e8s digeste<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barbera d&rsquo;Alba vinifi\u00e9 et \u00e9lev\u00e9 dans de grands foudres slov\u00e8nes. C&rsquo;est un vin \u00e0 la fois structur\u00e9, mais qui garde la finesse, le c\u00f4t\u00e9 a\u00e9rien des vins du domaine. Tr\u00e8s jolie d\u00e9finition de l&rsquo;aromatique, tout est d\u00e9taill\u00e9 et tr\u00e8s \u00e9l\u00e9gant. Un vin tr\u00e8s digeste<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3736],"product_tag":[],"class_list":["post-48189","product","type-product","status-publish","product_cat-vins","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BARBERA D&#039;ALBA BRICCO DEI MERLI - Mes Vendanges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BARBERA D&#039;ALBA BRICCO DEI MERLI - Mes Vendanges\" \/>\n<meta property=\"og:description\" content=\"Barbera d&rsquo;Alba vinifi\u00e9 et \u00e9lev\u00e9 dans de grands foudres slov\u00e8nes. C&rsquo;est un vin \u00e0 la fois structur\u00e9, mais qui garde la finesse, le c\u00f4t\u00e9 a\u00e9rien des vins du domaine. Tr\u00e8s jolie d\u00e9finition de l&rsquo;aromatique, tout est d\u00e9taill\u00e9 et tr\u00e8s \u00e9l\u00e9gant. Un vin tr\u00e8s digeste\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Vendanges\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T12:50:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\\\/\",\"name\":\"BARBERA D'ALBA BRICCO DEI MERLI - Mes Vendanges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\"},\"datePublished\":\"2022-08-02T15:34:21+00:00\",\"dateModified\":\"2023-12-05T12:50:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/vins\\\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.mesvendanges.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BARBERA D&#8217;ALBA BRICCO DEI MERLI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"name\":\"Mes Vendanges\",\"description\":\"Des journ\u00e9es enti\u00e8res dans les vignes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#organization\",\"name\":\"Mes Vendanges\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mesvendanges.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo-mesvendanges.jpg\",\"width\":851,\"height\":260,\"caption\":\"Mes Vendanges\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mesvendanges.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BARBERA D'ALBA BRICCO DEI MERLI - Mes Vendanges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/","og_locale":"fr_FR","og_type":"article","og_title":"BARBERA D'ALBA BRICCO DEI MERLI - Mes Vendanges","og_description":"Barbera d&rsquo;Alba vinifi\u00e9 et \u00e9lev\u00e9 dans de grands foudres slov\u00e8nes. C&rsquo;est un vin \u00e0 la fois structur\u00e9, mais qui garde la finesse, le c\u00f4t\u00e9 a\u00e9rien des vins du domaine. Tr\u00e8s jolie d\u00e9finition de l&rsquo;aromatique, tout est d\u00e9taill\u00e9 et tr\u00e8s \u00e9l\u00e9gant. Un vin tr\u00e8s digeste","og_url":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/","og_site_name":"Mes Vendanges","article_modified_time":"2023-12-05T12:50:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/","url":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/","name":"BARBERA D'ALBA BRICCO DEI MERLI - Mes Vendanges","isPartOf":{"@id":"https:\/\/www.mesvendanges.com\/en\/#website"},"datePublished":"2022-08-02T15:34:21+00:00","dateModified":"2023-12-05T12:50:39+00:00","breadcrumb":{"@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/barbera-dalba-bricco-dei-merli-cogno-elvio-2016-75cl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mesvendanges.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.mesvendanges.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"BARBERA D&#8217;ALBA BRICCO DEI MERLI"}]},{"@type":"WebSite","@id":"https:\/\/www.mesvendanges.com\/en\/#website","url":"https:\/\/www.mesvendanges.com\/en\/","name":"Mes Vendanges","description":"Des journ\u00e9es enti\u00e8res dans les vignes","publisher":{"@id":"https:\/\/www.mesvendanges.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesvendanges.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.mesvendanges.com\/en\/#organization","name":"Mes Vendanges","url":"https:\/\/www.mesvendanges.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","width":851,"height":260,"caption":"Mes Vendanges"},"image":{"@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product\/48189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/media?parent=48189"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_brand?post=48189"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_cat?post=48189"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_tag?post=48189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}