{"id":82031,"date":"2024-11-23T16:10:56","date_gmt":"2024-11-23T15:10:56","guid":{"rendered":"https:\/\/www.mesvendanges.com\/shop\/non%20class\u00e9\/la-fage-cosse-maisonneuve-2020-75cl\/"},"modified":"2026-06-01T20:38:39","modified_gmt":"2026-06-01T18:38:39","slug":"la-fage-cosse-maisonneuve-2020-75cl","status":"publish","type":"product","link":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/","title":{"rendered":"LA FAGE"},"content":{"rendered":"<p>Tr\u00e8s belle cuv\u00e9e de Cahors, issue de terroirs argilo-graveleux. Suppl\u00e9ment de corps et de profondeur dans ce vin dense et tonique. Beaucoup de fraicheur et d&#8217;allant en bouche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00e8s belle cuv\u00e9e de Cahors, issue de terroirs argilo-graveleux. Suppl\u00e9ment de corps et de profondeur dans ce vin dense et tonique. Beaucoup de fraicheur et d&#8217;allant en bouche.<\/p>\n","protected":false},"featured_media":82029,"template":"","meta":[],"product_cat":[3736],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LA FAGE - Mes Vendanges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA FAGE - Mes Vendanges\" \/>\n<meta property=\"og:description\" content=\"Tr\u00e8s belle cuv\u00e9e de Cahors, issue de terroirs argilo-graveleux. Suppl\u00e9ment de corps et de profondeur dans ce vin dense et tonique. Beaucoup de fraicheur et d&#8217;allant en bouche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Vendanges\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T18:38:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2024\/11\/cosse-maisonneuve-cahors-la-fage-2020-png.png\" \/>\n\t<meta property=\"og:image:width\" content=\"421\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mesvendanges.com\/en\/#organization\",\"name\":\"Mes Vendanges\",\"url\":\"https:\/\/www.mesvendanges.com\/en\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg\",\"contentUrl\":\"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg\",\"width\":851,\"height\":260,\"caption\":\"Mes Vendanges\"},\"image\":{\"@id\":\"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mesvendanges.com\/en\/#website\",\"url\":\"https:\/\/www.mesvendanges.com\/en\/\",\"name\":\"Mes Vendanges\",\"description\":\"Des journ\u00e9es enti\u00e8res dans les vignes\",\"publisher\":{\"@id\":\"https:\/\/www.mesvendanges.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mesvendanges.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#primaryimage\",\"url\":\"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2024\/11\/cosse-maisonneuve-cahors-la-fage-2020-png.png\",\"contentUrl\":\"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2024\/11\/cosse-maisonneuve-cahors-la-fage-2020-png.png\",\"width\":421,\"height\":1500},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/\",\"url\":\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/\",\"name\":\"LA FAGE - Mes Vendanges\",\"isPartOf\":{\"@id\":\"https:\/\/www.mesvendanges.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#primaryimage\"},\"datePublished\":\"2024-11-23T15:10:56+00:00\",\"dateModified\":\"2026-06-01T18:38:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mesvendanges.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/www.mesvendanges.com\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LA FAGE\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA FAGE - Mes Vendanges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/","og_locale":"fr_FR","og_type":"article","og_title":"LA FAGE - Mes Vendanges","og_description":"Tr\u00e8s belle cuv\u00e9e de Cahors, issue de terroirs argilo-graveleux. Suppl\u00e9ment de corps et de profondeur dans ce vin dense et tonique. Beaucoup de fraicheur et d&#8217;allant en bouche.","og_url":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/","og_site_name":"Mes Vendanges","article_modified_time":"2026-06-01T18:38:39+00:00","og_image":[{"width":421,"height":1500,"url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2024\/11\/cosse-maisonneuve-cahors-la-fage-2020-png.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.mesvendanges.com\/en\/#organization","name":"Mes Vendanges","url":"https:\/\/www.mesvendanges.com\/en\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2022\/02\/logo-mesvendanges.jpg","width":851,"height":260,"caption":"Mes Vendanges"},"image":{"@id":"https:\/\/www.mesvendanges.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.mesvendanges.com\/en\/#website","url":"https:\/\/www.mesvendanges.com\/en\/","name":"Mes Vendanges","description":"Des journ\u00e9es enti\u00e8res dans les vignes","publisher":{"@id":"https:\/\/www.mesvendanges.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesvendanges.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#primaryimage","url":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2024\/11\/cosse-maisonneuve-cahors-la-fage-2020-png.png","contentUrl":"https:\/\/www.mesvendanges.com\/wp-content\/uploads\/2024\/11\/cosse-maisonneuve-cahors-la-fage-2020-png.png","width":421,"height":1500},{"@type":"WebPage","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/","url":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/","name":"LA FAGE - Mes Vendanges","isPartOf":{"@id":"https:\/\/www.mesvendanges.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#primaryimage"},"datePublished":"2024-11-23T15:10:56+00:00","dateModified":"2026-06-01T18:38:39+00:00","breadcrumb":{"@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesvendanges.com\/fr\/boutique\/vins\/la-fage-cosse-maisonneuve-2020-75cl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mesvendanges.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.mesvendanges.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"LA FAGE"}]}]}},"_links":{"self":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product\/82031"}],"collection":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/media\/82029"}],"wp:attachment":[{"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/media?parent=82031"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_cat?post=82031"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mesvendanges.com\/fr\/wp-json\/wp\/v2\/product_tag?post=82031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}